{"id":3503,"date":"2026-02-11T11:08:46","date_gmt":"2026-02-11T11:08:46","guid":{"rendered":"https:\/\/lepanierdeleontine.fr\/accueil\/?p=3503"},"modified":"2026-02-11T11:08:46","modified_gmt":"2026-02-11T11:08:46","slug":"les-realisations-de-latelier-du-lundi-en-2025","status":"publish","type":"post","link":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/","title":{"rendered":"Les r\u00e9alisations de l&rsquo;Atelier du  lundi  en 2025"},"content":{"rendered":"\n<p><strong>Voici les r\u00e9alisations des Ateliers du lundi en 2025.  Ces ateliers continuent en 2026, venez nous rejoindre le lundi apr\u00e8s-midi de 13h30 \u00e0 15h30 \u00e0 l&rsquo;\u00e9picerie de Villefontaine.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#67ac2d\" class=\"has-inline-color\">Couture \u00e0 la main : petits sachets de lavande et porte-cartes<\/mark><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3504\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg\" alt=\"\" class=\"wp-image-3504\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3506\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-768x1024.jpg\" alt=\"\" class=\"wp-image-3506\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260105_151432-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3507\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-1024x768.jpg\" alt=\"\" class=\"wp-image-3507\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20260112_151909-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#67ac2d\" class=\"has-inline-color\">Couture \u00e0 la machine: sacs de transport pour tarte<\/mark><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3508\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-768x1024.jpg\" alt=\"\" class=\"wp-image-3508\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151516-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3509\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-1024x768.jpg\" alt=\"\" class=\"wp-image-3509\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250929_152752-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#67ac2d\" class=\"has-inline-color\">petits ballotins et maniques<\/mark><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3510\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-1024x768.jpg\" alt=\"\" class=\"wp-image-3510\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_152236-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3511\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-1024x768.jpg\" alt=\"\" class=\"wp-image-3511\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_152450-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3512\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-768x1024.jpg\" alt=\"\" class=\"wp-image-3512\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251006_162003-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#67ac2d\" class=\"has-inline-color\">Papiers, Cartons: cartes en relief, vide poche<\/mark><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3513\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-768x1024.jpg\" alt=\"\" class=\"wp-image-3513\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251013_160136-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3514\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-1024x768.jpg\" alt=\"\" class=\"wp-image-3514\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250616_154952-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3515\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-768x1024.jpg\" alt=\"\" class=\"wp-image-3515\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-768x1024.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-225x300.jpg 225w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-1152x1536.jpg 1152w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-1536x2048.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-1x1.jpg 1w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250512_151547-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#67ac2d\" class=\"has-inline-color\">Bracelet br\u00e9silien et D\u00e9corations de No\u00ebl<\/mark><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3517\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-1024x768.jpg\" alt=\"\" class=\"wp-image-3517\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_153133-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3518\" src=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-1024x768.jpg\" alt=\"\" class=\"wp-image-3518\" srcset=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-1024x768.jpg 1024w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-300x225.jpg 300w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-768x576.jpg 768w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-1536x1152.jpg 1536w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-2048x1536.jpg 2048w, https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20251124_162127-1x1.jpg 1w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici les r\u00e9alisations des Ateliers du lundi en 2025. Ces ateliers continuent en 2026, venez nous rejoindre le lundi apr\u00e8s-midi de 13h30 \u00e0 15h30 \u00e0 l&rsquo;\u00e9picerie de Villefontaine. Couture \u00e0 la main : petits sachets de lavande et porte-cartes Couture \u00e0 la machine: sacs de transport pour tarte petits ballotins et maniques Papiers, Cartons: cartes&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,26],"tags":[],"class_list":["post-3503","post","type-post","status-publish","format-standard","hentry","category-animation","category-villefontaine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les r\u00e9alisations de l&#039;Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire<\/title>\n<meta name=\"description\" content=\"Les r\u00e9alisations de l&#039;Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les r\u00e9alisations de l&#039;Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9alisations de l&#039;Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Le panier de L\u00e9ontine \u00e9picerie solidaire\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T11:08:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/#website\",\"url\":\"https:\/\/lepanierdeleontine.fr\/accueil\/\",\"name\":\"Le panier de L\u00e9ontine \u00e9picerie solidaire\",\"description\":\"Epicerie sociale &amp; solidaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lepanierdeleontine.fr\/accueil\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg\",\"contentUrl\":\"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#webpage\",\"url\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/\",\"name\":\"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire\",\"isPartOf\":{\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#primaryimage\"},\"datePublished\":\"2026-02-11T11:08:46+00:00\",\"dateModified\":\"2026-02-11T11:08:46+00:00\",\"author\":{\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/#\/schema\/person\/6c61305ecd5902a90472d8af750ef33c\"},\"description\":\"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire\",\"breadcrumb\":{\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lepanierdeleontine.fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les r\u00e9alisations de l&rsquo;Atelier du lundi en 2025\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/#\/schema\/person\/6c61305ecd5902a90472d8af750ef33c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/lepanierdeleontine.fr\/accueil\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","description":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","og_description":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","og_url":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/","og_site_name":"Le panier de L\u00e9ontine \u00e9picerie solidaire","article_published_time":"2026-02-11T11:08:46+00:00","og_image":[{"url":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg"}],"twitter_card":"summary","twitter_misc":{"\u00c9crit par":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/#website","url":"https:\/\/lepanierdeleontine.fr\/accueil\/","name":"Le panier de L\u00e9ontine \u00e9picerie solidaire","description":"Epicerie sociale &amp; solidaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lepanierdeleontine.fr\/accueil\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg","contentUrl":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-content\/uploads\/2026\/02\/20250303_152359-768x1024.jpg"},{"@type":"WebPage","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#webpage","url":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/","name":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","isPartOf":{"@id":"https:\/\/lepanierdeleontine.fr\/accueil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#primaryimage"},"datePublished":"2026-02-11T11:08:46+00:00","dateModified":"2026-02-11T11:08:46+00:00","author":{"@id":"https:\/\/lepanierdeleontine.fr\/accueil\/#\/schema\/person\/6c61305ecd5902a90472d8af750ef33c"},"description":"Les r\u00e9alisations de l'Atelier du lundi en 2025 - Le panier de L\u00e9ontine \u00e9picerie solidaire","breadcrumb":{"@id":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/les-realisations-de-latelier-du-lundi-en-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lepanierdeleontine.fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Les r\u00e9alisations de l&rsquo;Atelier du lundi en 2025"}]},{"@type":"Person","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/#\/schema\/person\/6c61305ecd5902a90472d8af750ef33c","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/lepanierdeleontine.fr\/accueil\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/posts\/3503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/comments?post=3503"}],"version-history":[{"count":5,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/posts\/3503\/revisions"}],"predecessor-version":[{"id":3525,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/posts\/3503\/revisions\/3525"}],"wp:attachment":[{"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/media?parent=3503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/categories?post=3503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lepanierdeleontine.fr\/accueil\/wp-json\/wp\/v2\/tags?post=3503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}